{"id":1980,"date":"2025-12-17T13:00:46","date_gmt":"2025-12-17T12:00:46","guid":{"rendered":"https:\/\/uks.eus\/?post_type=katalogoa&#038;p=1980"},"modified":"2025-12-17T13:03:36","modified_gmt":"2025-12-17T12:03:36","slug":"otra-vuelta-de-tuerca-engranajes-feministas-para-una-universidad-emancipadora","status":"publish","type":"katalogoa","link":"https:\/\/uks.eus\/es\/katalogoa\/otra-vuelta-de-tuerca-engranajes-feministas-para-una-universidad-emancipadora\/","title":{"rendered":"Otra Vuelta de Tuerca: engranajes feministas para una universidad emancipadora"},"content":{"rendered":"<p style=\"text-align: left;\">De las ganas de compartir aprendizajes y generar alternativas para el montaje de la universidad<br \/>\nque so\u00f1amos surge esta gu\u00eda, impulsada por Emaus Gizarte Fundazioa y elaborada por Aradia Cooperativa y que forma parte de todo un conjunto de productos articulados<br \/>\ndesde los que seguir profundizando en la construcci\u00f3n de un modelo universitario y social<br \/>\nalternativo.<\/p>\n<p style=\"text-align: left;\">Estas p\u00e1ginas recogen orientaciones que nos permiten dar una vuelta<br \/>\nde tuerca al modelo universitario desde los marcos que nos ofrecen los feminismos en di\u00e1logo con<br \/>\notros movimientos sociales. Pues queremos rescatar el imaginario de una instituci\u00f3n viva, capaz<br \/>\nde responder a las emergencias que nos acucian y de convertirse en la locomotora del cambio<br \/>\nsocial que deber\u00eda ser como lugar del saber y de la exploraci\u00f3n.<\/p>\n<p><a href=\"https:\/\/uks.eus\/wp-content\/uploads\/2025\/12\/Otra-vuelta-de-tuerca_online-5.pdf\">CONSULTAR Y DESCARGAR LA GU\u00cdA AQU\u00cd<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De las ganas de compartir aprendizajes y generar alternativas para el montaje de la universidad que so\u00f1amos surge esta gu\u00eda, impulsada por Emaus Gizarte Fundazioa y elaborada por Aradia Cooperativa y que forma parte de todo un conjunto de productos articulados desde los que seguir profundizando en la construcci\u00f3n de un modelo universitario y social [&hellip;]<\/p>\n","protected":false},"featured_media":1981,"template":"","format":"standard","categories":[58,69],"tipo":[78],"class_list":{"0":"post-1980","1":"katalogoa","2":"type-katalogoa","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-calidad-universitaria-es","8":"category-feminismos-es","9":"tipo-publicacion-es","10":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/katalogoa\/1980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/katalogoa"}],"about":[{"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/types\/katalogoa"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/media\/1981"}],"wp:attachment":[{"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/media?parent=1980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/categories?post=1980"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/uks.eus\/es\/wp-json\/wp\/v2\/tipo?post=1980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}